{"id":313,"count":1,"description":"","link":"https:\/\/www.breeze-technologies.de\/de\/blog\/tag\/emission-de\/","name":"emission","slug":"emission-de","taxonomy":"post_tag","meta":[],"yoast_head":"<title>emission Archives - Breeze Technologies<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"emission Archives - Breeze Technologies\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.breeze-technologies.de\/de\/blog\/tag\/emission-de\/\" \/>\n<meta property=\"og:site_name\" content=\"Breeze Technologies\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@projectbreeze\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.breeze-technologies.de\\\/de\\\/blog\\\/tag\\\/emission-de\\\/\",\"url\":\"https:\\\/\\\/www.breeze-technologies.de\\\/de\\\/blog\\\/tag\\\/emission-de\\\/\",\"name\":\"emission Archives - Breeze Technologies\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.breeze-technologies.de\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.breeze-technologies.de\\\/de\\\/blog\\\/tag\\\/emission-de\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.breeze-technologies.de\\\/de\\\/blog\\\/tag\\\/emission-de\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.breeze-technologies.de\\\/de\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"emission\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.breeze-technologies.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.breeze-technologies.de\\\/de\\\/\",\"name\":\"Breeze Technologies\",\"description\":\"Environmental Sensor Solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.breeze-technologies.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.breeze-technologies.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.breeze-technologies.de\\\/de\\\/#organization\",\"name\":\"Breeze Technologies\",\"url\":\"https:\\\/\\\/www.breeze-technologies.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.breeze-technologies.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.breeze-technologies.de\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Breeze-Logo-Normal-Web.png\",\"contentUrl\":\"https:\\\/\\\/www.breeze-technologies.de\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Breeze-Logo-Normal-Web.png\",\"width\":2932,\"height\":976,\"caption\":\"Breeze Technologies\"},\"image\":{\"@id\":\"https:\\\/\\\/www.breeze-technologies.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/breezetechnologies\\\/\",\"https:\\\/\\\/x.com\\\/projectbreeze\",\"https:\\\/\\\/instagram.com\\\/breezetechnologies\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/breeze-technologies\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqRNWyXf5yexIRTzLvY9Zqw\"]}]}<\/script>","yoast_head_json":{"title":"emission Archives - Breeze Technologies","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"emission Archives - Breeze Technologies","og_url":"https:\/\/www.breeze-technologies.de\/de\/blog\/tag\/emission-de\/","og_site_name":"Breeze Technologies","twitter_card":"summary_large_image","twitter_site":"@projectbreeze","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.breeze-technologies.de\/de\/blog\/tag\/emission-de\/","url":"https:\/\/www.breeze-technologies.de\/de\/blog\/tag\/emission-de\/","name":"emission Archives - Breeze Technologies","isPartOf":{"@id":"https:\/\/www.breeze-technologies.de\/de\/#website"},"breadcrumb":{"@id":"https:\/\/www.breeze-technologies.de\/de\/blog\/tag\/emission-de\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.breeze-technologies.de\/de\/blog\/tag\/emission-de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.breeze-technologies.de\/de\/home\/"},{"@type":"ListItem","position":2,"name":"emission"}]},{"@type":"WebSite","@id":"https:\/\/www.breeze-technologies.de\/de\/#website","url":"https:\/\/www.breeze-technologies.de\/de\/","name":"Breeze Technologies","description":"Environmental Sensor Solutions","publisher":{"@id":"https:\/\/www.breeze-technologies.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.breeze-technologies.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.breeze-technologies.de\/de\/#organization","name":"Breeze Technologies","url":"https:\/\/www.breeze-technologies.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.breeze-technologies.de\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.breeze-technologies.de\/wp-content\/uploads\/2017\/12\/Breeze-Logo-Normal-Web.png","contentUrl":"https:\/\/www.breeze-technologies.de\/wp-content\/uploads\/2017\/12\/Breeze-Logo-Normal-Web.png","width":2932,"height":976,"caption":"Breeze Technologies"},"image":{"@id":"https:\/\/www.breeze-technologies.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/breezetechnologies\/","https:\/\/x.com\/projectbreeze","https:\/\/instagram.com\/breezetechnologies\/","https:\/\/www.linkedin.com\/company\/breeze-technologies","https:\/\/www.youtube.com\/channel\/UCqRNWyXf5yexIRTzLvY9Zqw"]}]}},"_links":{"self":[{"href":"https:\/\/www.breeze-technologies.de\/de\/wp-json\/wp\/v2\/tags\/313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.breeze-technologies.de\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.breeze-technologies.de\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.breeze-technologies.de\/de\/wp-json\/wp\/v2\/posts?tags=313"},{"href":"https:\/\/www.breeze-technologies.de\/de\/wp-json\/wp\/v2\/portfolio?tags=313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}